{"id":9812,"date":"2024-01-02T13:42:44","date_gmt":"2024-01-02T12:42:44","guid":{"rendered":"http:\/\/brosa.es\/comentarios-ultimas-leyes-fiscales-3\/"},"modified":"2024-01-02T13:48:50","modified_gmt":"2024-01-02T12:48:50","slug":"comentarios-ultimas-leyes-fiscales-2023","status":"publish","type":"post","link":"https:\/\/brosa.es\/en\/comentarios-ultimas-leyes-fiscales-2023\/","title":{"rendered":"Comentarios \u00faltimas leyes fiscales"},"content":{"rendered":"<p>Como es habitual en el mes de diciembre, se acumula toda una serie de normativa para que pueda entrar en vigor a 1 de enero de 2024.<\/p>\n<p>En esta Circular comentaremos tres normas tributarias publicadas con anterioridad al 21 de diciembre:<\/p>\n<ul>\n<li>D. 1008\/2023 de 5 de diciembre (BOE de diciembre) por el cual se modifica el Reglamento del Impuesto sobre las Personas F\u00edsicas y el Reglamento del Impuesto sobre Sociedades.<\/li>\n<li>D.L. 6\/2023 de 19 de diciembre (BOE 20 de diciembre), esta norma introduce algunas modificaciones en la Ley 49\/2002 de 23 de diciembre, de r\u00e9gimen fiscal de las entidades sin fines lucrativos y de los incentivos fiscales al mecenazgo.<\/li>\n<li>Orden HFP\/1359\/2023 de 19 de diciembre (BOE 21 de diciembre), por la que se desarrollan para el a\u00f1o 2024 el m\u00e9todo de estimaci\u00f3n objetiva del Impuesto sobre la Renta de las Personas F\u00edsicas y el r\u00e9gimen especial simplificado del Impuesto sobre el Valor A\u00f1adido.<\/li>\n<\/ul>\n<h2>1. Modificaciones en el Reglamento del Impuesto sobre la Renta, para el ejercicio 2024. Rd1008\/2023 de 5 de diciembre<\/h2>\n<p><strong>\u00a0<\/strong>Se introducen modificaciones en materia de retribuciones en especie, deducci\u00f3n por maternidad, obligaci\u00f3n de declarar, pagos a cuenta y r\u00e9gimen especial aplicable a desplazados a territorio espa\u00f1ol. Todas las modificaciones entran en vigor y tienen efectos desde el 7 de diciembre.<\/p>\n<h3>1.1 Exenci\u00f3n de rendimientos de trabajo derivados de la entrega de acciones o participaciones a trabajadores<\/h3>\n<p><strong>\u00a0<\/strong>En el supuesto de la entrega de acciones o participaciones a trabajadores de empresas emergentes, no se exigir\u00e1 que la oferta se realice en las mismas condiciones para todos los trabajadores de la misma.<\/p>\n<h3>1.2 Deducci\u00f3n por maternidad<\/h3>\n<p><strong>\u00a0<\/strong>Se adapta el contenido de la norma a la nueva regulaci\u00f3n legal en la que se ha ampliado el colectivo beneficiario de la misma.<\/p>\n<h3>1.3 Obligaci\u00f3n de declarar<\/h3>\n<p>Se incorpora la obligaci\u00f3n legal de declarar para aquellas personas f\u00edsicas que hubieran estado de alta como trabajadores por cuenta propia o aut\u00f3nomos, con independencia del importe de su facturaci\u00f3n.<\/p>\n<p>Cuando se obtengan rendimientos de trabajo de m\u00e1s de un pagador, se eleva el rendimiento del umbral inferior de 14.000 \u20ac a 15.000 \u20ac.<\/p>\n<h3>1.4 Tipo de retenci\u00f3n de los rendimientos de trabajo derivados de la elaboraci\u00f3n de obras literarias, art\u00edsticas o cient\u00edficas<\/h3>\n<p>Se establece un tipo de retenci\u00f3n reducido del 7%, cuando el volumen de tales rendimientos correspondientes al ejercicio inmediato anterior sea inferior a 15.000 \u20ac anuales.<\/p>\n<h3>1.5 Tipo de retenci\u00f3n de la propiedad intelectual<\/h3>\n<p>Se aclara que el tipo de retenci\u00f3n de la propiedad intelectual, sea cual sea su calificaci\u00f3n, ser\u00e1 del 15%, salvo cuando resulte de aplicaci\u00f3n el tipo reducido del 7%.<\/p>\n<h3>1.6 R\u00e9gimen especial de trabajadores desplazados a territorio espa\u00f1ol<\/h3>\n<p>Como consecuencia de los cambios introducidos en la LIRPF por la Ley 28\/2022 de 21 de diciembre de creaci\u00f3n y crecimiento de empresas emergentes, donde ya se efectu\u00f3 una extensi\u00f3n del r\u00e9gimen de impatriados a nuevos supuestos, como los relacionados con el teletrabajo, emprendedores, profesionales o contribuyentes que realizan actividad de formaci\u00f3n, investigaci\u00f3n, desarrollo e innovaci\u00f3n, o familiares acompa\u00f1antes, se introducen en el cap\u00edtulo que regula este r\u00e9gimen especial diversas modificaciones para adaptar su contenido a la regulaci\u00f3n legal.<\/p>\n<p>El cap\u00edtulo que se denomina \u201cR\u00e9gimen especial aplicable a los trabajadores desplazados a territorio espa\u00f1ol\u201d pasa a denominarse \u201cR\u00e9gimen aplicable a los trabajadores, profesionales, emprendedores e inversores desplazados a territorio espa\u00f1ol.\u201d<\/p>\n<h2>2. Modificaciones en el Reglamento del Impuesto sobre Sociedades, para el ejercicio 2024. Rd1008\/2023 de 5 de diciembre<\/h2>\n<p>La \u00fanica modificaci\u00f3n que se produce en este Reglamento es de tipo t\u00e9cnico, se introduce la exenci\u00f3n de retener a los intereses percibidos por la entidad de contrapartida central y por sus miembros, en las infraestructuras de post contrataci\u00f3n y en r\u00e9gimen de aportaci\u00f3n de garant\u00eda para cubrir los riesgos de incumplimiento en la liquidaci\u00f3n de las operaciones sobre instrumentos financieros.<\/p>\n<h2>3. Modificaciones en la ley 49\/2002 de 23 de diciembre, del R\u00e9gimen fiscal de las entidades sin finalidades lucrativas y de los incentivos al mecenazgo<\/h2>\n<h3>3.1 Aplicaci\u00f3n de nuevas exenciones<\/h3>\n<ul>\n<li><strong>\u00a0<\/strong>Se ampl\u00eda el \u00e1mbito subjetivo de las entidades exentas a aquellas que se dediquen a la defensa de los animales.<\/li>\n<li>Se incluye como explotaci\u00f3n econ\u00f3mica exenta la inserci\u00f3n socio laboral de personas en riesgo de exclusi\u00f3n social.<\/li>\n<\/ul>\n<h3>3.2 Nuevos donativos deducibles<\/h3>\n<ul>\n<li>Se incluye un nuevo supuesto que da derecho a practicar deducciones por donativos: la cesi\u00f3n del uso de un bien mueble o inmueble, por un tiempo determinado, realizado sin contraprestaci\u00f3n.<\/li>\n<\/ul>\n<h3>3.3 Impuesto sobre la Renta de las Personas F\u00edsicas<\/h3>\n<ul>\n<li>Se eleva la base de la deducci\u00f3n y los porcentajes: sobre una base de 250 \u20ac el 80%, para el resto de base el 40%.<\/li>\n<li>Si en los dos periodos impositivos inmediatos anteriores, se hubieran realizado donativos a favor de la misma entidad y el importe de la donaci\u00f3n fuera igual o superior en cada periodo, podr\u00e1 aplicarse un 45% de deducci\u00f3n sobre el importe que exceda de los 250 \u20ac.<\/li>\n<\/ul>\n<h3>3.4 Impuesto sobre Sociedades<\/h3>\n<ul>\n<li>Se incrementa el porcentaje de deducci\u00f3n aplicable que pasa del 35% al 40%.<\/li>\n<li>Si en los dos periodos impositivos inmediatos anteriores, se hubieran realizado donativos a favor de la misma entidad y el importe de la donaci\u00f3n fuera igual o superior en cada periodo, podr\u00e1 aplicarse un 50% de deducci\u00f3n, en lugar del 40%.<\/li>\n<\/ul>\n<h2>4. Modificaciones Orden Hfp\/1359\/2023 de 19 de diciembre, de Desarrollo para el 2024 del sistema de tributaci\u00f3n por m\u00f3dulos en IRPF y en IVA<\/h2>\n<h3>4.1 Modificaciones en IRPF<\/h3>\n<ul>\n<li>Se establece una reducci\u00f3n del 5% sobre el rendimiento de m\u00f3dulo para el ejercicio 2024.<\/li>\n<li>Para las actividades agr\u00edcolas y ganaderas se establece una reducci\u00f3n sobre el rendimiento neto previo del 35% del precio de adquisici\u00f3n de gas\u00f3leo agr\u00edcola y en el 15% del precio de adquisici\u00f3n de fertilizantes.<\/li>\n<li>Se mantienen las reducciones especiales aplicadas en el 2022 y 2023 para las actividades realizadas en la isla de la Palma.<\/li>\n<\/ul>\n<h3>4.2 Modificaciones en IVA<\/h3>\n<ul>\n<li>En cuanto a IVA, no se producen cambios.<\/li>\n<\/ul>\n<p>La Circular Fiscal 4\/2023 est\u00e1 disponible para su descarga siguiendo este enlace: <a href=\"https:\/\/brosa.es\/wp-content\/uploads\/2024\/01\/CF042023.pdf\">Circular Fiscal 4\/2023 Diciembre<\/a>.<\/p>\n<br \/>\n","protected":false},"excerpt":{"rendered":"<p>Como es habitual en el mes de diciembre, se acumula toda una serie de normativa para que pueda entrar en vigor a 1 de enero de 2024. En esta Circular comentaremos tres normas tributarias publicadas con anterioridad al 21 de diciembre: D. 1008\/2023 de 5 de diciembre (BOE de diciembre) por el cual se modifica&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[221],"tags":[],"_links":{"self":[{"href":"https:\/\/brosa.es\/en\/wp-json\/wp\/v2\/posts\/9812"}],"collection":[{"href":"https:\/\/brosa.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brosa.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brosa.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/brosa.es\/en\/wp-json\/wp\/v2\/comments?post=9812"}],"version-history":[{"count":1,"href":"https:\/\/brosa.es\/en\/wp-json\/wp\/v2\/posts\/9812\/revisions"}],"predecessor-version":[{"id":9817,"href":"https:\/\/brosa.es\/en\/wp-json\/wp\/v2\/posts\/9812\/revisions\/9817"}],"wp:attachment":[{"href":"https:\/\/brosa.es\/en\/wp-json\/wp\/v2\/media?parent=9812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brosa.es\/en\/wp-json\/wp\/v2\/categories?post=9812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brosa.es\/en\/wp-json\/wp\/v2\/tags?post=9812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}