{"id":9897,"date":"2024-03-14T18:45:01","date_gmt":"2024-03-14T17:45:01","guid":{"rendered":"http:\/\/brosa.es\/notificaciones-electronicas-en-el-ambito-procesal\/"},"modified":"2024-03-14T18:45:01","modified_gmt":"2024-03-14T17:45:01","slug":"notificaciones-electronicas-en-el-ambito-procesal","status":"publish","type":"post","link":"https:\/\/brosa.es\/en\/notificaciones-electronicas-en-el-ambito-procesal\/","title":{"rendered":"Notificaciones electr\u00f3nicas  en el \u00e1mbito procesal"},"content":{"rendered":"<style><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><br \/>h2 {<br \/>    font-size: 1.6em;<br \/>line-height: 1.2;<br \/>}<br \/>h3 {<br \/>    font-size: 1.2em;<br \/>line-height: 1.2;<br \/>}<br \/><\/style>\n<p>A partir del 20\/3\/2024 las empresas y aquellos que deben relacionarse electr\u00f3nicamente con la Administraci\u00f3n deber\u00e1n controlar las notificaciones recibidas por medios electr\u00f3nicos y, en caso de no acceder a ellas en el plazo de 3 d\u00edas, se les tendr\u00e1 por notificados produciendo plenos efectos y empezando a correr los plazos correspondientes.<\/p>\n<p>As\u00ed se regula la modificaci\u00f3n de la Ley de Enjuiciamiento Civil que, en esta cuesti\u00f3n, realiza el Real Decreto-Ley 6\/2023 por el que se aprueban medidas urgentes para la ejecuci\u00f3n del Plan de Recuperaci\u00f3n, Transformaci\u00f3n y Resiliencia en materia de servicio p\u00fablico de justicia, funci\u00f3n p\u00fablica, r\u00e9gimen local y mecenazgo, implementa medidas de eficiencia procesal con la finalidad de reducir la litigiosidad y agilizar los procedimientos.<\/p>\n<p>Desde un punto de vista pr\u00e1ctico de quien puede ser parte en un proceso judicial (p.e. si te demandan), adquiere una vital relevancia esta nueva regulaci\u00f3n sobre notificaciones procesales electr\u00f3nicas. Al establecer notificaciones por medios electr\u00f3nicos para quienes deben relacionarse electr\u00f3nicamente con la Administraci\u00f3n, se introduce una nueva obligaci\u00f3n: controlar las plataformas de notificaciones para evitar perder oportunidades de defensa por desconocimiento de que se haya producido una notificaci\u00f3n.<strong>\u00a0<\/strong><\/p>\n<h2>1. Comunicaciones procesales por medios electr\u00f3nicos<\/h2>\n<h3>1.1 A partir del <strong>pr\u00f3ximo 20\/3\/2024 <\/strong>la <strong>regla general <\/strong>es el <strong>uso de medios electr\u00f3nicos <\/strong>con la Administraci\u00f3n de Justicia para:<\/h3>\n<p>a) Aquellas <strong>entidades que tengan la obligaci\u00f3n de relacionarse electr\u00f3nicamente con la Administraci\u00f3n de Justicia<\/strong>, entre los que se encuentran:<\/p>\n<ul>\n<li>las personas jur\u00eddicas<\/li>\n<li>entidades sin personalidad jur\u00eddica<\/li>\n<li>quien ejerza una actividad profesional que requiera colegiaci\u00f3n obligatoria, para los tr\u00e1mites y actuaciones que realicen con la Administraci\u00f3n de Justicia en ejercicio de dicha actividad profesional<\/li>\n<li>quien represente a un interesado obligado a relacionarse electr\u00f3nicamente<\/li>\n<\/ul>\n<p>b) Aquellos que <strong>se hubieran obligado contractualmente al uso de sistemas electr\u00f3nicos para resolver litigios derivados del contrato<\/strong>, salvo en contratos de adhesi\u00f3n con consumidores y usuarios.<\/p>\n<p>Una previsi\u00f3n contractual \u00e9sta que deviene interesante frente a aquellos que no tienen la obligaci\u00f3n de relacionarse electr\u00f3nicamente con la Administraci\u00f3n, pues tal y como veremos seguidamente puede facilitar y agilizar la notificaci\u00f3n del inicio del procedimiento (normalmente la demanda).<\/p>\n<p>c) Aquellos que <strong>voluntariamente aceptan <\/strong>una notificaci\u00f3n electr\u00f3nica <strong>u opten por el uso <\/strong>de estos medios<\/p>\n<h3>1.2 La <strong>excepci\u00f3n <\/strong>es la notificaci\u00f3n en papel en el domicilio del destinatario a la <strong>persona f\u00edsica<\/strong>, que no se haya obligado contractualmente o admita voluntariamente la notificaci\u00f3n electr\u00f3nica.<\/h3>\n<p>Una vez el destinatario ya est\u00e9 <strong>comparecido en el procedimiento habiendo designado procurador<\/strong>, la comunicaci\u00f3n seguir\u00e1 efectu\u00e1ndose a trav\u00e9s del procurador. Ahora bien, mientras no se conste comparecido en un procedimiento mediante procurador, las comunicaciones (para los sujetos del apartado 1.1) se efectuar\u00e1n por medios electr\u00f3nicos, incluida:<\/p>\n<ul>\n<li>la primera notificaci\u00f3n (emplazamiento o citaci\u00f3n), p.e notificaciones de demandas; y<\/li>\n<li>la notificaci\u00f3n de realizaci\u00f3n o intervenci\u00f3n personal en determinadas actuaciones procesales, p.e, citaciones como testigo, requerimientos de aportaci\u00f3n de documentos etc.<\/li>\n<\/ul>\n<h2>2. Primer emplazamiento judicial por medios telem\u00e1ticos y comunicaciones con partes no representadas por procurador<\/h2>\n<h3>2.1 A partir del <strong>pr\u00f3ximo 20\/3\/2024 ya no recibir\u00e1n en su domicilio y en papel el primer emplazamiento o comunicaci\u00f3n judicial <\/strong>las personas que:<\/h3>\n<ul>\n<li>est\u00e1n obligadas <strong>a relacionarse electr\u00f3nicamente con la Administraci\u00f3n, ya sea por obligaci\u00f3n legal <\/strong>(ver apartado 1.1.a) <strong>o contractual <\/strong>(personas f\u00edsicas, salvo consumidores en contratos de adhesi\u00f3n)<\/li>\n<li>no estando obligadas &#8211;<strong>personas f\u00edsicas<\/strong>&#8211; <strong>han aceptado relacionarse electr\u00f3nicamente <\/strong>con la Administraci\u00f3n <strong>o han accedido a la notificaci\u00f3n <\/strong>electr\u00f3nica que se les ha puesto a su disposici\u00f3n.<\/li>\n<\/ul>\n<p>En estos casos, si son objeto de <strong>demanda<\/strong>, \u00e9sta se les <strong>notificar\u00e1 por medios electr\u00f3nicos <\/strong>mediante su comparecencia en la <strong>Carpeta Justicia o en la Sede Judicial Electr\u00f3nica a trav\u00e9s de la Direcci\u00f3n Electr\u00f3nica Habilitada \u00danica (DEH\u00fa) o sistemas equivalentes que usan algunas comunidades aut\u00f3nomas<\/strong>, <strong>o cualquier otro medio electr\u00f3nico que se establezca reglamentariamente<\/strong>. Igualmente, con estas personas, se seguir\u00e1 este mismo procedimiento para todas las notificaciones durante el procedimiento en los que opten no usar procurador por no ser necesario.<\/p>\n<p>A estos efectos, en principio, el \u00f3rgano de administraci\u00f3n de justicia correspondiente que haga la comunicaci\u00f3n enviar\u00e1 un aviso al dispositivo electr\u00f3nico de su destinatario o a la direcci\u00f3n de correo electr\u00f3nico que les conste, inform\u00e1ndole de la puesta a su disposici\u00f3n del acto de comunicaci\u00f3n en la sede judicial electr\u00f3nica o en la Direcci\u00f3n Electr\u00f3nica Habilitada \u00danica.<\/p>\n<p>En el primer emplazamiento o citaci\u00f3n o cuando se les notifique la intervenci\u00f3n personal en una actuaci\u00f3n judicial, si no acceden a la misma en el plazo de 3 d\u00edas desde que la Administraci\u00f3n de Justicia se la ha puesto telem\u00e1ticamente a su disposici\u00f3n, se publicar\u00e1 en el Tabl\u00f3n Edictal Judicial \u00danico d\u00e1ndosele por notificada a la empresa, empezando a correr el plazo correspondiente.<\/p>\n<p>En consecuencia <strong>es indispensable controlar las plataformas electr\u00f3nicas y el Tabl\u00f3n Edictal Judicial \u00danico (TEJU) <\/strong>con la finalidad de garantizar el cumplimiento de las obligaciones legales que se derivan de dichas notificaciones, y muy especialmente por lo que a los plazos procesales respecta.<\/p>\n<p>Llamamos la atenci\u00f3n sobre la <strong>conveniencia de suscribir los \u201csistemas de alerta\u201d <\/strong>que tienen estas plataformas electr\u00f3nicas, incluido el TJUE, con la finalidad de ser avisado mediante correo electr\u00f3nico de la puesta a disposici\u00f3n de una notificaci\u00f3n facilitando el acceso a la misma en t\u00e9rmino. De todos modos, resaltamos que <strong>la falta de env\u00edo del correspondiente aviso por el \u00d3rgano de Administracion de Justicia <\/strong>de su puesta a disposici\u00f3n <strong>no impide <\/strong>que <strong>el acto de comunicaci\u00f3n <\/strong>sea considerado plenamente v\u00e1lido (Art 160 LEC).<\/p>\n<h3>2.2 En caso de <strong>sujetos no obligados a la relaci\u00f3n electr\u00f3nica<\/strong>, como las <strong>personas f\u00edsicas<\/strong>, se les notificar\u00e1 en su domicilio y en papel o en forma telem\u00e1tica, si bien \u00e9sta \u00faltima solo ser\u00e1 v\u00e1lida si es aceptada voluntariamente por el destinatario.<\/h3>\n<p>La Circular Procesal 1\/2024 est\u00e1 disponible para su descarga siguiendo este enlace: <a href=\"https:\/\/brosa.es\/wp-content\/uploads\/2024\/03\/CP202401.pdf\" target=\"_blank\" rel=\"noopener\">Circular Procesal 1\/2024 Marzo<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir del 20\/3\/2024 las empresas y aquellos que deben relacionarse electr\u00f3nicamente con la Administraci\u00f3n deber\u00e1n controlar las notificaciones recibidas por medios electr\u00f3nicos y, en caso de no acceder a ellas en el plazo de 3 d\u00edas, se les tendr\u00e1 por notificados produciendo plenos efectos y empezando a correr los plazos correspondientes. As\u00ed se regula&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[221],"tags":[],"_links":{"self":[{"href":"https:\/\/brosa.es\/en\/wp-json\/wp\/v2\/posts\/9897"}],"collection":[{"href":"https:\/\/brosa.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brosa.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brosa.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/brosa.es\/en\/wp-json\/wp\/v2\/comments?post=9897"}],"version-history":[{"count":0,"href":"https:\/\/brosa.es\/en\/wp-json\/wp\/v2\/posts\/9897\/revisions"}],"wp:attachment":[{"href":"https:\/\/brosa.es\/en\/wp-json\/wp\/v2\/media?parent=9897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brosa.es\/en\/wp-json\/wp\/v2\/categories?post=9897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brosa.es\/en\/wp-json\/wp\/v2\/tags?post=9897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}