{"id":9705,"date":"2023-01-13T16:16:59","date_gmt":"2023-01-13T15:16:59","guid":{"rendered":"http:\/\/brosa.es\/modificaciones-tributarias-de-la-ley-de-presupuestos-para-el-ejercicio-2023\/"},"modified":"2023-01-13T16:16:59","modified_gmt":"2023-01-13T15:16:59","slug":"modificaciones-tributarias-de-la-ley-de-presupuestos-para-el-ejercicio-2023","status":"publish","type":"post","link":"https:\/\/brosa.es\/fr\/modificaciones-tributarias-de-la-ley-de-presupuestos-para-el-ejercicio-2023\/","title":{"rendered":"Modificaciones tributarias de la ley de presupuestos para el ejercicio 2023"},"content":{"rendered":"<p>En el Bolet\u00edn Oficial del Estado de 24 de diciembre de 2022 se public\u00f3 la Ley 31\/2022, de 23 de diciembre, de Presupuestos Generales del Estado para el a\u00f1o 2023.<\/p>\n<p>En dicha Ley se han incluido modificaciones que afectan a la normativa tributaria de los principales impuestos, las cuales ser\u00e1n expuestas a continuaci\u00f3n.<\/p>\n<p>Contin\u00faan vigentes las introducidas en ejercicios anteriores y no modificadas por la presente Ley.<\/p>\n<p>A continuaci\u00f3n comentaremos las modificaciones m\u00e1s importantes, que ser\u00e1n aplicables a partir del 1 de enero del 2023.<\/p>\n<h2>1. IMPUESTO SOBRE LA RENTA DE LAS PERSONAS F\u00cdSICAS<\/h2>\n<h3>1.1 Reducci\u00f3n por obtenci\u00f3n de rendimientos de trabajo<\/h3>\n<p>A partir del 1 de enero del 2023, se eleva la cuant\u00eda de la reducci\u00f3n por obtenci\u00f3n de rendimientos de trabajo y de los umbrales de renta, desde y hasta donde resulte aplicable. Los contribuyentes con rendimientos netos de trabajo inferiores a 19.747,50\u20ac, (antes 16.825\u20ac) que no tengan rentas distintas de las de trabajo superiores a 6.500\u20ac, minoran el rendimiento neto de trabajo en las siguientes cuant\u00edas:<\/p>\n<ul>\n<li>6.498 \u20ac, para rendimientos de trabajo inferiores a 14.047,50\u20ac<\/li>\n<li>6.498\u20ac menos el resultado de multiplicar por 1,14 la diferencia entre el rendimiento de trabajo y 14.047,50\u20ac, si dichos rendimientos son inferiores a 19.747,50\u20ac<\/li>\n<\/ul>\n<h3>1.2 Reducci\u00f3n obtenci\u00f3n rendimientos en estimaci\u00f3n directa simplificada<\/h3>\n<p>A partir del 1 de enero del 2023 se aplicar\u00e1n las mismas reducciones del apartado anterior, para rendimientos inferiores a 19.747,50\u20ac, que no tengan rentas distintas de \u00e9stas superiores a 6.500\u20ac.<\/p>\n<h3>1.3 Umbrales de declaraci\u00f3n<\/h3>\n<p>Se eleva el umbral inferior de la obligaci\u00f3n de declarar respecto a perceptores de varios rendimientos de trabajo a 15.000\u20ac anuales (antes 14.000\u20ac).<\/p>\n<h3>1.4 Pr\u00f3rroga de los l\u00edmites estimaci\u00f3n objetiva en IRPF<\/h3>\n<p>Se prorrogan para el 2023 los l\u00edmites excluyentes del m\u00e9todo de estimaci\u00f3n objetiva, establecidos en el 2021, quedan fijados en 250.000\u20ac y 125.000\u20ac.<\/p>\n<p>La magnitud de 250.000\u20ac para actividades agr\u00edcolas, ganaderas y forestales, tambi\u00e9n se prorroga indefinidamente para actividades de estimaci\u00f3n objetiva.<\/p>\n<p>Los contribuyentes podr\u00e1n reducir el rendimiento de m\u00f3dulos obtenido en el 2023 en un 10%.<\/p>\n<h3>1.5 Planes de pensiones<\/h3>\n<p>Se fijan nuevos l\u00edmites en la reducci\u00f3n de la base imponible de las aportaciones y contribuciones a sistemas de previsi\u00f3n social, con vigencia indefinida.<\/p>\n<ul>\n<li>El conjunto de las reducciones practicadas a favor de un mismo contribuyente se mantiene en 1.500\u20ac para el ejercicio 2023, de tal forma que el importe m\u00e1ximo no podr\u00e1 exceder de dicho importe para que pueda beneficiarse de la deducci\u00f3n.<\/li>\n<li>Se mantiene en 8.500\u20ac la reducci\u00f3n m\u00e1xima de las aportaciones empresariales a estos sistemas de previsi\u00f3n social, permiti\u00e9ndose, como novedad, que el trabajador realice aportaciones a dichos planes de pensiones hasta completar los 8.500\u20ac. Para el ejercicio 2023 se establecen l\u00edmites a la aportaci\u00f3n que el trabajador realice, a partir de 1.500\u20ac, el l\u00edmite ser\u00e1 el que resulte de multiplicar la aportaci\u00f3n empresarial por 1.<\/li>\n<\/ul>\n<h3>1.6 Tipos de gravamen del ahorro<\/h3>\n<p>Se regulan nuevos tipos de gravamen, a\u00f1adiendo dos tramos a la base liquidable:<\/p>\n<ul>\n<li>Entre 200.000\u20ac y 300.000\u20ac se aplica un tipo del 27% (antes 26%)<\/li>\n<li>A partir de 300.000\u20ac se aplica un tipo del 28% (antes 26%)<\/li>\n<\/ul>\n<h3>1.7 Deducci\u00f3n por maternidad<\/h3>\n<p>Se ampl\u00eda la aplicaci\u00f3n de la deducci\u00f3n por maternidad por hijos de 0 a 3 a\u00f1os, para las madres que est\u00e9n percibiendo una prestaci\u00f3n por desempleo o que tengan al menos 30 d\u00edas cotizados.<\/p>\n<h3>1.8 Retenciones<\/h3>\n<ul>\n<li>Se modifican los tipos de retenciones sobre rendimientos de la propiedad intelectual, los anticipos de derechos de autor pasar\u00e1n del 15% al 7%, as\u00ed como tambi\u00e9n el tipo de retenci\u00f3n general que pasa del 19% al 15%.<\/li>\n<li>Tipo de retenciones enero 2023. Durante el mes de enero, las retenciones e ingresos a cuenta a practicar deber\u00e1n realizarse con arreglo a la normativa vigente a 31 de diciembre del 2022.<\/li>\n<li>En los rendimientos satisfechos a partir del 1 de febrero del 2023, el pagador deber\u00e1 calcular el tipo de retenci\u00f3n tomando en consideraci\u00f3n la normativa vigente a partir de 1 de enero de 2023.<\/li>\n<\/ul>\n<h2>2. IMPUESTO SOBRE SOCIEDADES<\/h2>\n<p>Con efectos 1 de enero del 2023, se adaptan las siguientes medidas:<\/p>\n<h3>2.1 Tipo de gravamen de empresas de reducida dimensi\u00f3n<\/h3>\n<p>Se rebaja en 2 puntos el tipo de gravamen aplicable aquellas entidades que tengan una cifra de negocios inferior a 1.000.000\u20ac, en el periodo impositivo anterior, pasando a tributar al 23%, en lugar del 25%.<\/p>\n<p>Cuando la entidad fuere de nueva creaci\u00f3n, el importe neto de la cifra de negocios se referir\u00e1 al primer per\u00edodo impositivo en que se desarrolle efectivamente la actividad.<\/p>\n<h3>2.2 Amortizaci\u00f3n acelerada de veh\u00edculos<\/h3>\n<p>Las inversiones en determinados veh\u00edculos nuevos previstos en la nueva D.A.18 LIS, (tipolog\u00edas FCV, FCHV, BEV, REEV y PHEV), podr\u00e1n amortizarse multiplicando por 2 el coeficiente de amortizaci\u00f3n m\u00e1ximo previsto en las tablas, siempre que entren en funcionamiento en los periodos que se inicien en los a\u00f1os 2023, 2024 y 2025.<\/p>\n<h2>3. IMPUESTO SOBRE EL VALOR A\u00d1ADIDO<\/h2>\n<h3>3.1 Lugar de realizaci\u00f3n de determinadas prestaciones de servicios. Reglas especiales. Art\u00ba70 LIVA<\/h3>\n<p>Se realiza la armonizaci\u00f3n de la normativa del IVA a la normativa comunitaria.<\/p>\n<ul>\n<li>Se suprime la aplicaci\u00f3n de la regla especial de uso efectivo en las prestaciones de servicios entre empresarios de aquellos sectores y actividades generadoras del derecho a la deducci\u00f3n, mientras que se mantiene su aplicaci\u00f3n en sectores que no generan tal derecho, como el sector financiero y el de seguros.<\/li>\n<\/ul>\n<h3>3.2 Inversi\u00f3n de sujeto pasivo. Art.84 LIVA<\/h3>\n<ul>\n<li>Se extiende la aplicaci\u00f3n del mecanismo de inversi\u00f3n de sujeto pasivo, para operaciones o entidades no establecidas, con car\u00e1cter general. Salvo las excepciones siguientes:\n<ul>\n<li>Prestaciones de servicios del arrendamiento de inmuebles sujetas al Impuesto, realizadas por empresarios no establecidos.<\/li>\n<li>Prestaciones de servicios de intermediaci\u00f3n en el arrendamiento de inmuebles, realizados por empresarios no establecidos.<\/li>\n<li>Se incluye la aplicaci\u00f3n de la inversi\u00f3n de sujeto pasivo a las entregas de desechos y desperdicios de pl\u00e1stico y de materia textil, y se modifican las reglas referentes al sujeto pasivo para que sea de aplicaci\u00f3n la regla de inversi\u00f3n de \u00e9ste a las entregas de estos residuos y materiales de recuperaci\u00f3n.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h3>3.3 Modificaci\u00f3n base imponible por cr\u00e9ditos incobrables. Art.80 LIVA<\/h3>\n<p>a) Se rebaja a 50\u20ac (antes 300\u20ac) el importe m\u00ednimo de la base imponible de la operaci\u00f3n, que se puede modificar, cuando el destinatario moroso tenga la condici\u00f3n de consumidor final.<\/p>\n<p>b) Se flexibiliza el procedimiento, incorporando la posibilidad de sustituir la reclamaci\u00f3n judicial o requerimiento notarial previo al deudor, por cualquier otro medio de prueba que acredite la comunicaci\u00f3n fehaciente de la reclamaci\u00f3n.<\/p>\n<p>c) Se extiende a 6 meses el plazo para proceder a la recuperaci\u00f3n del IVA desde que el cr\u00e9dito es declarado incobrable.<\/p>\n<p>d) Se permitir\u00e1 la modificaci\u00f3n de la base imponible en caso de cr\u00e9ditos incobrables como consecuencia de un proceso de insolvencia declarada por un \u00f3rgano jurisdiccional de otro estado miembro.<\/p>\n<h3>3.4 Tipo reducido del 4%. Art.91 LIVA<\/h3>\n<p>Pasan a tributar al tipo reducido del 4%, en lugar del 10%, los tampones, compresas, protegeslips y los anticonceptivos no medicinales.<\/p>\n<h3>3.5 Comercio electr\u00f3nico. Art.68 LIVA<\/h3>\n<p>Se llevan a cabo una serie de ajustes t\u00e9cnicos para definir de forma m\u00e1s precisa las reglas referentes al lugar de realizaci\u00f3n de las ventas a distancia intracomunitarias de bienes y el c\u00e1lculo del l\u00edmite que permite seguir tributando en origen por estas operaciones. Contin\u00faa fij\u00e1ndose el umbral de 10.000\u20ac, aunque \u00e9ste no se aplicar\u00e1 si el env\u00edo de bienes se realiza desde un estado miembro diferente del establecimiento.<\/p>\n<h3>3.6 L\u00edmites para la aplicaci\u00f3n del r\u00e9gimen simplificado y r\u00e9gimen especial de la agricultura, ganader\u00eda y pesca, en el ejercicio 2023<\/h3>\n<p>Se prorrogan un a\u00f1o m\u00e1s los l\u00edmites excluyentes para la aplicaci\u00f3n de estos reg\u00edmenes especiales. Se mantiene el l\u00edmite de 250.000\u20ac de volumen de ingresos del ejercicio anterior.<\/p>\n<h2>4. IMPUESTO SOBRE TRANSMISIONES PATRIMONIALES Y ACTOS JUR\u00cdDICOS DOCUMENTADOS<\/h2>\n<p>Se actualiza al 2% la escala de transmisiones y rehabilitaciones de grandezas y t\u00edtulos nobiliarios.<\/p>\n<h2>5. IMPUESTO SOBRE ACTIVIDADES ECONOMICAS<\/h2>\n<p>Con efectos 1 de enero de 2023, se crean los siguientes grupos de actividad nuevos:<\/p>\n<p>&#8211; Grupo 848 \u201cServicios de oficina flexible, coworking y centros de negocios\u201d<br \/>\n&#8211; Grupo 861 \u201cArtistas falleros\u201d<br \/>\n&#8211; Grupo 864 \u201cEscritores y Guionistas\u201d<br \/>\n&#8211; Grupo 869 \u201cOtros profesionales relacionadas con actividades art\u00edsticas y culturales\u201d<br \/>\n&#8211; Grupo 899 \u201cGu\u00edas de monta\u00f1a\u201d<br \/>\n&#8211; Grupo 034 \u201cCompositores, letristas y arreglistas\u201d<\/p>\n<h2>6. IMPUESTO SOBRE EL INCREMENTO DEL VALOR DE LOS TERRENOS DE NATURALEZA URBANA<\/h2>\n<p>Se actualizan los importes de los coeficientes m\u00e1ximos aplicables sobre el valor de los terrenos en funci\u00f3n del periodo de generaci\u00f3n del incremento de valor, para la determinaci\u00f3n de la base imponible. El coeficiente oscilar\u00e1 entre el 0,15 para periodos iguales o inferiores al a\u00f1o el 0,45, para periodos iguales o superiores a 20 a\u00f1os.<\/p>\n<h2>7. APLAZAMIENTOS Y FRACCIONAMIENTOS DE DEUDAS TRIBUTARIAS<\/h2>\n<p>Se clarifican las deudas y sanciones tributarias, que pueden ser objeto de aplazamiento o fraccionamiento y se ampl\u00edan los plazos que podr\u00e1n objeto de los mismos, seg\u00fan las circunstancias del acreedor tributario:<\/p>\n<p>a) Plazo m\u00e1ximo de 6 meses, cuando las deudas sean de cuant\u00eda inferior a 30.000\u20ac, y se trate de Comunidades de Bienes y Sociedades Civiles en general.<\/p>\n<p>b) Plazo m\u00e1ximo de 12 meses, cuando las deudas sean de cuant\u00eda inferior a 30.000\u20ac, cuando se trate de personas f\u00edsicas o sociedades mercantiles.<\/p>\n<p>c) Plazo m\u00e1ximo de 24 meses, cuando las deudas se garanticen conforme al art. 82.1, p\u00e1rrafo segundo y tercero de la LGT, mediante hipoteca, prenda o fianza personal.<\/p>\n<p>d) Plazo m\u00e1ximo de 36 meses, cuando las deudas se garanticen conforme al art. 82.1, p\u00e1rrafo primero de la LGT, mediante aval o certificado de seguro de cauci\u00f3n.<\/p>\n<h2>8. BENEFICIOS FISCALES PARA LA REALIZACI\u00d3N DE ACONTECIMIENTOS DE INTERES GENERAL Y ACTIVIDADES PRIORITARIAS DE MECENAZGO<\/h2>\n<p>Se actualiza la relaci\u00f3n de actividades prioritarias de mecenazgo y acontecimientos de excepcional inter\u00e9s p\u00fablico, con actividades previstas para el 2023.<\/p>\n<h2>9. OTRAS DISPOSICIONES CON INCIDENDIA TRIBUTARIA<\/h2>\n<p>&#8211; INTER\u00c9S LEGAL DE DINERO<\/p>\n<p>Se mantiene el inter\u00e9s legal del dinero en el 3,25%, para el ejercicio 2023 (se incrementa el tipo en un 0,25%)<\/p>\n<p>&#8211; INTER\u00c9S DE DEMORA<\/p>\n<p>Se mantiene el inter\u00e9s de demora en el 4,0625, para el ejercicio 2023 (se incrementa el tipo en un 0,3125 %)<\/p>\n<p>&#8211; IPREM (Indicador P\u00fablico de Renta de Efectos M\u00faltiples)<\/p>\n<p>Los importes de este indicador para el 2023, se fijan en los importes siguientes:<\/p>\n<ul>\n<li>IPREM, diario, 20\u20ac<\/li>\n<li>IPREM, mensual, 600\u20ac<\/li>\n<li>IPREM, ANUAL, 7.200\u20ac<\/li>\n<li>En los supuestos en que la referencia al salario m\u00ednimo interprofesional haya sido sustituida por la referencia al IPREM, la cuant\u00eda anual ser\u00e1 de 8.400\u20ac<\/li>\n<\/ul>\n<p>La Circular Fiscal 1\/2023 est\u00e1 disponible para su descarga siguiendo este enlace: <a href=\"https:\/\/brosa.es\/wp-content\/uploads\/2023\/01\/CF0123.pdf\" target=\"_blank\" rel=\"noopener\">Circular Fiscal 1\/2023 Enero<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el Bolet\u00edn Oficial del Estado de 24 de diciembre de 2022 se public\u00f3 la Ley 31\/2022, de 23 de diciembre, de Presupuestos Generales del Estado para el a\u00f1o 2023. En dicha Ley se han incluido modificaciones que afectan a la normativa tributaria de los principales impuestos, las cuales ser\u00e1n expuestas a continuaci\u00f3n. Contin\u00faan vigentes&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[536],"tags":[582],"_links":{"self":[{"href":"https:\/\/brosa.es\/fr\/wp-json\/wp\/v2\/posts\/9705"}],"collection":[{"href":"https:\/\/brosa.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brosa.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brosa.es\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/brosa.es\/fr\/wp-json\/wp\/v2\/comments?post=9705"}],"version-history":[{"count":0,"href":"https:\/\/brosa.es\/fr\/wp-json\/wp\/v2\/posts\/9705\/revisions"}],"wp:attachment":[{"href":"https:\/\/brosa.es\/fr\/wp-json\/wp\/v2\/media?parent=9705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brosa.es\/fr\/wp-json\/wp\/v2\/categories?post=9705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brosa.es\/fr\/wp-json\/wp\/v2\/tags?post=9705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}